{"id":3309,"date":"2020-06-25T15:23:41","date_gmt":"2020-06-25T15:23:41","guid":{"rendered":"http:\/\/www.jab.lv\/forum\/?p=3309"},"modified":"2020-06-22T10:19:42","modified_gmt":"2020-06-22T10:19:42","slug":"tchernobyl-rencontre-avec-guillaume-herbaut","status":"publish","type":"post","link":"https:\/\/www.jab.lv\/forum\/2020\/06\/25\/tchernobyl-rencontre-avec-guillaume-herbaut\/","title":{"rendered":"Tchernobyl Rencontre Avec Guillaume Herbaut"},"content":{"rendered":"<p>Micha\u00ebl Zumstein est photojournaliste. Son terrain cest lAfrique : il y photographie les relations avec lOccident des histoires de commerce, de trafics, deldorado et de charity business mais aussi la guerre, quil raconte comme personne, cest \u00e0 dire avec le moins de sang et le plus de sens possible. De ses cinq s\u00e9jours en Centrafrique, il a rapport\u00e9 la s\u00e9rie De Terreur et de larmes. C\u00e9tait pour le journal Le Monde et \u00e7a a touch\u00e9 du monde : Picture Of the Year, Lens Culture Award, Swiss Press Photo Award et une expo au festival Visa pour lImage de Perpignan. Perpignan cest l\u00e0 o\u00f9 tout avait commenc\u00e9, par hasard : il avait 19 ans et avait \u00e9t\u00e9 \u00e9bloui les r\u00e9cits en images de Bouvet et Nachtwey. Il a aussi un passeport suisse, ce qui est pratique pour se balader dans les pays o\u00f9 ne vont pas les touristes. En poursuivant votre navigation sur ce site, vous acceptez lutilisation de cookies. Fran\u00e7ois Hollande nest pas C\u00e9sar Birotteau, mais il fallait un \u00e9crivain pour nous expliquer comment un homme soutenu par la France enti\u00e8re au mois de novembre peut, au printemps, se trouver dans une situation si d\u00e9solante. Jean dOrmesson a limmense privil\u00e8ge davoir une \u0153uvre mais aussi une vie. Il observe la com\u00e9die humaine aux premi\u00e8res loges et ne cesse de r\u00e9fl\u00e9chir, sans pr\u00e9jug\u00e9, aux mouvements du monde. Le regard quil porte sur les fiascos de la d\u00e9ch\u00e9ance et de la loi El Khomri est s\u00e9v\u00e8re mais profond\u00e9ment juste. Ce quil pointe, cest le triomphe des demi-habiles et des promesses destrade. Or, rappelle-t-il, dans sa langue inimitable: La France nest pas un conseil r\u00e9gional. Savur-Mohyla 5 octobre 2014 16h55 Photo Guillaume Herbaut <img decoding=\"async\" src=\"http:\/\/img.over-blog.com\/650x919\/2\/03\/17\/22\/Club-litteraire\/Invit_soiree-Jadan-le-25-oct-2014.jpg\" alt=\"tchernobyl rencontre avec guillaume herbaut\" align=\"center\"> Cependant, le r\u00e9acteur est toujours actif et la dalle de b\u00e9ton qui le soutient menace de se fissurer. Plus grave, leau d\u00e9vers\u00e9e par les pompiers pour \u00e9teindre lincendie a noy\u00e9 les sous-structures, mena\u00e7ant ainsi lint\u00e9grit\u00e9 et le pilotage des trois autres r\u00e9acteurs de la centrale. Le professeur diagnostique que si le c\u0153ur en fusion atteint la nappe deau accumul\u00e9e par lintervention des pompiers, une explosion de vapeur est susceptible de se produire et de diss\u00e9miner des \u00e9l\u00e9ments radioactifs \u00e0 une tr\u00e8s grande distance. En effet, la fusion du combustible et des structures m\u00e9talliques a form\u00e9 un sur le plancher situ\u00e9 sous le r\u00e9acteur. Leau pouvait \u00eatre drain\u00e9e en ouvrant des vannes d\u00e9vacuation. Cependant, les soupapes qui la contr\u00f4laient \u00e9taient sous leau, situ\u00e9es dans un couloir inond\u00e9 dans le sous-sol. Ainsi, des volontaires en combinaison de plong\u00e9e, avec des respirateurs pour la protection contre les a\u00e9rosols radioactifs et \u00e9quip\u00e9s de dosim\u00e8tres, plongent dans leau radioactive pour ouvrir les vannes,. Ces hommes sont les ing\u00e9nieurs Alexei Ananenko et Valeri Bezpalov qui savaient o\u00f9 se trouvaient les vannes, accompagn\u00e9s du superviseur de quart Boris Baranov. Les trois hommes savaient que c\u00e9tait une mission suicide, ils ont subi une forte et seraient morts peu de temps apr\u00e8s, selon de nombreux articles en langue anglaise, des livres et le docufiction de la Surviving Disaster-Chernobyl Nuclear. Certaines sources ont \u00e9galement affirm\u00e9 \u00e0 tort quils \u00e9taient morts dans lusine. Cependant les recherches dAndrew Leatherbarrow, auteur du livre Tchernobyl 01:23:40, ont d\u00e9termin\u00e9 que lhistoire fr\u00e9quemment racont\u00e9e \u00e9tait une exag\u00e9ration grossi\u00e8re : Alexei Ananenko continue de travailler dans lindustrie de l\u00e9nergie nucl\u00e9aire et pense quil y a beaucoup de folklore autour de Tchernobyl dans les m\u00e9dia. Bien que Valeri Bezpalov ait \u00e9t\u00e9 retrouv\u00e9 encore vivant par Leatherbarrow, Baranov \u00e2g\u00e9 de 65 ans, a v\u00e9cu jusquen 2005 et est mort dune insuffisance cardiaque, selon une source en langue russe. COLLECTIF PENSER LURBAIN PAR LIMAGE, Re-prises  Cest Tchernobyl qui a provoqu\u00e9 ces questionnements sur limage et mon parcours. Je me suis dit je fais de la photo pour r\u00e9fl\u00e9chir et donner \u00e0 r\u00e9fl\u00e9chir. Jai fait des d\u00e9couvertes par rapport \u00e0 moi-m\u00eame. On ne sait pas ce quon cherche, ce quon veut raconter, et \u00e0 la fin, \u00e7a devient \u00e9vident, \u00e7a arrive.  Guillaume Herbaut: A chaque fois que je pars dans des endroits qui sont durs, comme Tchernobyl, il y a la radioactivit\u00e9, je serais dans un endroit socialement hyper dur, avec des violences permanentes, je vais rencontrer des anciens prisonniers qui se r\u00e9fugient dans les zones interdites, il y a la pr\u00e9sence de lalcool tous les soirs dans les boites de nuits, il y a des bagarres. Et il y a le danger physique de la radioactivit\u00e9. Quand je pars, jai peur. Quand je vais en Ukraine, dans les zones de conflits, avant, jai peur. Et heureusement! La peur, cest une information. A partir du moment o\u00f9 on a plus peur, on est en danger. Donc il faut le savoir, et aussi savoir comment g\u00e9rer sa peur. Quand j\u00e9tais \u00e0 Prypyat photo 4, une qui est \u00e0 3km de la centrale de Tchernobyl, qui a \u00e9t\u00e9 \u00e9vacu\u00e9e du jour au lendemain en 1986. Aujourdhui cest une ville fant\u00f4me et c\u00e9tait une ville de 20 mille habitants, donc quand on y va, cest The Walking Dead, il ny a personne, la v\u00e9g\u00e9tation prend le dessus. Un jour j\u00e9tais \u00e0 5h du matin sur le toit dun immeuble et jentendais une meute de loups hurler \u00e0 la mort par exemple, et il y a des gens qui entrent clandestinement dans la zone, on appelle \u00e7a des stalkers, qui vivent en lisi\u00e8re de zone interdite, et qui vont voler \u00e0 lint\u00e9rieur de la zone. Donc en fait quand on \u00e9coute la ville, on peut entendre des gens taper du m\u00e9tal, le chercher etc. Donc cest une vision apocalyptique. En plus il y a la radioactivit\u00e9 mais moi je connais bien cette ville. Et un jour, je me suis promen\u00e9 dans la ville, et javais plus peur. Et je me suis rendu compte Tiens l\u00e0 jai plus peur, il faut que jarr\u00eate, il faut que je parte, cest trop dangereux pour moi maintenant. Quand jai pas peur, je me sit quil y a un probl\u00e8me. <img decoding=\"async\" src=\"http:\/\/ukrainedouestenest.blog.lemonde.fr\/files\/2015\/03\/DSC_7147-1.jpg\" alt=\"tchernobyl rencontre avec guillaume herbaut\" align=\"right\"> Les familles ont beau se claquemurer, rehausser les cl\u00f4tures des jardins de leurs maisons de plusieurs m\u00e8tres, ils finiront par \u00eatre rattrap\u00e9s. En 2010, un vieillard de 80 ans a \u00e9t\u00e9 assassin\u00e9 pour une mort remontant \u00e0 67 ans auparavant. <img decoding=\"async\" src=\"http:\/\/www.broad.missedthesale.com\/media\/cache\/home_slide\/vign_groupeentier.jpg\" alt=\"tchernobyl rencontre avec guillaume herbaut\" align=\"right\"> CRAC OCCITANIE Pyr\u00e9n\u00e9es-M\u00e9diterran\u00e9e 26 Quai Aspirant Herber 34200 S\u00e8te France Jeudi 14 avril-Inzinzac Lochrist 56-Cin\u00e9ma le Vulcain-Semaine de lArm\u00e9nie : en collaboration avec le lyc\u00e9e Victor Hugo dHennebont, en pr\u00e9sence d\u00e9crivain, de plasticien, le vice pr\u00e9sident du Fonds Arm\u00e9nien en France, le r\u00e9alisateur Mathieu Zeitindjioglou viendra pr\u00e9senter son film en avant-premi\u00e8re Le fils du marchand dolives-20h30 Catalogue et Studio photo Festival Circulations 2017 GUILLAUME HERBAUT. La zone de Tchernobyl, d\u00e9flagration narrative It was during one of his last trips to the forbidden Zone that Guillaume Herbaut produced this series of photographs. His numerous visits, to identical looted apartments, made him realise that the only thing that remained demonstrating the residents presence were the remaining front doors. Le Figaro Premium vous offre depuis un an Le Figaro et ses magazines au format num\u00e9rique. Loccasion de d\u00e9couvrir ou red\u00e9couvrir ces articles qui vous permettent chaque jour dapprofondir lactualit\u00e9. .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>tchernobyl rencontre avec guillaume herbaut<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/3309"}],"collection":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/comments?post=3309"}],"version-history":[{"count":1,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/3309\/revisions"}],"predecessor-version":[{"id":3310,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/3309\/revisions\/3310"}],"wp:attachment":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/media?parent=3309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/categories?post=3309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/tags?post=3309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}