{"id":6158,"date":"2020-06-30T06:29:21","date_gmt":"2020-06-30T06:29:21","guid":{"rendered":"http:\/\/www.jab.lv\/forum\/?p=6158"},"modified":"2020-06-24T01:27:56","modified_gmt":"2020-06-24T01:27:56","slug":"ma-rencontre-avec-christ","status":"publish","type":"post","link":"https:\/\/www.jab.lv\/forum\/2020\/06\/30\/ma-rencontre-avec-christ\/","title":{"rendered":"Ma Rencontre Avec Christ"},"content":{"rendered":"<p>A partir de l\u00e0, ce nest plus une voix que jentendais, mais mille, dont la plupart \u00e9taient loin d\u00eatre bienveillantes. Il sagissait de leur r\u00e9pondre de mani\u00e8re \u00e0 ne pas me laisser d\u00e9molir. L\u00e9criture a jou\u00e9 un r\u00f4le consid\u00e9rable. Ces voix malveillantes ne se taisent pas pour autant, mais elles ont trouv\u00e9 \u00e0 qui parler. Jai \u00e9t\u00e9 \u00e9lev\u00e9e avec une m\u00e8re tr\u00e8s croyante qui a toujours \u00e9t\u00e9 un exemple de charit\u00e9 et damour. Elle avait pig\u00e9 le truc! Mon p\u00e8re \u00e9tait m\u00e9decin g\u00e9n\u00e9raliste \u00e0 Levallois et Maman faisait venir des sans-domicile durant la nuit pour quils dorment dans la salle dattente du cabinet et leur faisait \u00e0 manger. Elle a eu lintelligence de nous parler de Dieu sans jamais rien nous imposer. C\u00e9tait tr\u00e8s intelligent de sa part. Et quand javais 14 ans, alors que je ne suis pas du matin, je prenais mon v\u00e9lo et plus tard ma moto et avant de partir au coll\u00e8ge, je me rendais de Levallois jusquau Sacr\u00e9-C\u0153ur de Montmartre pour assister \u00e0 la messe de 7 h avec les religieuses. Ces s\u0153urs sont vraiment devenues des amies : elles mont vu grandir et elles ont connu toute mon \u00e9volution de com\u00e9dienne. -Nous avons pr\u00e9par\u00e9 quelque chose qui est sur le point darriver J\u00e9sus-Christ ma accord\u00e9 le pardon de tous mes p\u00e9ch\u00e9s. Devenez membre et faites vous une nouvelle id\u00e9e de la lecture Seigneur, tu nous connais par notre nom et tu nous appelles par notre nom. Tu nous invites \u00e0 touvrir la porte de notre c\u0153ur, tu nous invites \u00e0 partager le Royaume avec toi, \u00e0 partager ta Vie. Nous savons que tu ne viens pas \u00e0 nous parce que nous aurions \u00e9t\u00e9 justes ou aurions fait juste, mais tout simplement parce que tu nous aimes. Alors, Seigneur, viens \u00e0 nous! car par lui nous avons les uns et les autres acc\u00e8s aupr\u00e8s du P\u00e8re, dans un m\u00eame Esprit. <img decoding=\"async\" src=\"http:\/\/jesus83marie.j.e.pic.centerblog.net\/399534b2.gif\" alt=\"ma rencontre avec christ\" align=\"center\"> <img decoding=\"async\" src=\"http:\/\/www.subject.serenitynowmassagetherapy.com\/img\/400\/5a0db0b4b43c9-sarl-c-probat-montmirail-51210-CDV-400.jpg\" alt=\"ma rencontre avec christ\" align=\"right\"> Mon c\u0153ur est debout, o Dieu, mon c\u0153ur est debout ; je chanterai et je te louerai. R\u00e9veille-toi, ma gloire! R\u00e9veillez-vous, harpe et cithare! Je r\u00e9veillerai laurore! Je te louerai, Seigneur, parmi les peuples, et je chanterai ta gloire parmi les nations! Car ta bont\u00e9 s\u00e9l\u00e8ve jusquau ciel, et ta v\u00e9rit\u00e9 jusquaux nuages. Apr\u00e8s la chirurgie, les m\u00e9decins mont administr\u00e9 un m\u00e9dicament qui \u00e9tait nouveau sur le march\u00e9, et jai r\u00e9agi quand j\u00e9tais \u00e0 lh\u00f4pital. Mon mari est arriv\u00e9 et ma ramen\u00e9e \u00e0 notre foyer \u00e0 Houston TX. Ma belle-m\u00e8re gardait les enfants. Je suis all\u00e9e dans ma chambre \u00e0 coucher, et jai pens\u00e9 que je faisais un accident vasculaire c\u00e9r\u00e9bral  T\u00e9moignage. \u00c0 Vernon, elle raconte avoir rencontr\u00e9 J\u00e9sus lors dune exp\u00e9rience de mort imminente T\u00e9moignage. Natalie Saracco raconte avoir rencontr\u00e9 J\u00e9sus lors dune exp\u00e9rience de mort imminente survenue apr\u00e8s un accident de la route. LEuroise est samedi 6 avril 2019 au soir \u00e0 la coll\u00e9giale de Vernon pour parler de ses fois et de sa mission. Tout ce que vous voulez que les hommes fassent pour vous, faites-le de m\u00eame pour eux, car cest la loi et les proph\u00e8tes. Matthieu 7:12 Verset biblique. Accepter ma foi a \u00e9t\u00e9 difficile puisque je devais \u00e9couter mon c\u0153ur, mes sentiments et non mon esprit ding\u00e9nieur pour lequel tout devait \u00eatre rationnel, scientifique. A cette \u00e9poque, jai presque regrett\u00e9 de ne pas avoir \u00e9t\u00e9 baptis\u00e9e jeune, ce qui maurait \u00e9vit\u00e9 une telle remise en question. Puis jai compris que ce cheminement, bien que difficile, \u00e9tait une chance puisquil mobligeait \u00e0 minterroger et surtout \u00e0 mettre des mots sur ce que je ressentais. Mettre des mots sur ce que je ressens, est finalement ce qui a \u00e9t\u00e9 et qui est toujours le plus difficile dans ma d\u00e9marche. Tout au long de cette pr\u00e9paration au mariage et le 5 septembre 2009, lors de notre messe de mariage, cest avec une r\u00e9elle conviction que pour notre couple. LEuroise, inconsciente, raconte avoir senti la chaleur quitter son corps et s\u00eatre retrouv\u00e9e, au milieu de nulle part, nez \u00e0 nez avec le Christ. Il pleurait tellement! Son visage \u00e9tait d\u00e9form\u00e9 par la douleur. Son sacr\u00e9 c\u0153ur avait quitt\u00e9 sa poitrine. Il pleurait des larmes de sang. Ce nest que le froid de la nuit, les bruits de la rue, les v\u00e9hicules passant \u00e0 c\u00f4t\u00e9 de moi, qui me firent revenir dans le temps pr\u00e9sent. Javais, sans aucun doute, v\u00e9cu un moment d\u00e9ternit\u00e9, car je navais aucune notion du temps qui s\u00e9tait \u00e9coul\u00e9. En tout cas, j\u00e9tais devenu quelquun dautre. Lamour de J\u00e9sus pour moi avait compl\u00e8tement boulevers\u00e9 ma vie. Je savais que je ne pourrais plus jamais vivre comme je lavais fait jusqu\u00e0 pr\u00e9sent. <img decoding=\"async\" src=\"http:\/\/bcs.fltr.ucl.ac.be\/FE\/28\/Egypt_MM\/Egyptien\/IMAG\/LarronsS.jpg\" alt=\"ma rencontre avec christ\" align=\"left\"> Tr\u00e9s beau t\u00e9moignage,nous avons u grand Dieu remplit damour,Dieu te b\u00e9nisse ma soeur en Christ Marie Noelle  Le jour de la rencontre, Peter comprend que le Saint-Esprit lui demande d\u00eatre audacieux avec Mohammad. Il lui dit : Notre Dieu nest pas le tien. Dabord ce quil faut retenir cest quon ne p\u00eache pas par Omission ni involontairement ni par le fait des autres. Tout est confus, le visage, les voix, je comprends les mots, mais je ne me sens pas revenue tout \u00e0 fait. Jai envie de pleurer, je ne suis pas heureuse d\u00eatre revenue. Ici na\u00eet la communaut\u00e9 de pri\u00e8re : d\u00e9j\u00e0 les premiers chr\u00e9tiens vivaient en communaut\u00e9 et priaient ensemble. Aujourdhui, exception faite des monast\u00e8res, couvents ou autres communaut\u00e9s de la\u00efcs comme les Foyers de Charit\u00e9, les chr\u00e9tiens vivent g\u00e9n\u00e9ralement seuls ou en famille-une forme de communaut\u00e9 plus r\u00e9duite qui peut aussi \u00eatre lobjet de. Nous avons cependant conserv\u00e9 cette n\u00e9cessit\u00e9 de la pri\u00e8re collective, qui nous unit dans notre foi : le sacrement de leucharistie, c\u00e9l\u00e9br\u00e9 pendant la messe, est une occasion pour les chr\u00e9tiens de se retrouver r\u00e9guli\u00e8rement et de prier ensemble. Le est \u00e9galement r\u00e9cit\u00e9 au cours de la messe ; en le r\u00e9citant nous proclamons ce qui constitue le socle de la foi de notre Eglise. Avec ta voix pure qui nous dit : Je suis moi-m\u00eame en vous! .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ma rencontre avec christ<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/6158"}],"collection":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/comments?post=6158"}],"version-history":[{"count":1,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/6158\/revisions"}],"predecessor-version":[{"id":6159,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/posts\/6158\/revisions\/6159"}],"wp:attachment":[{"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/media?parent=6158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/categories?post=6158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jab.lv\/forum\/wp-json\/wp\/v2\/tags?post=6158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}